{"id":3921,"date":"2012-09-05T21:39:09","date_gmt":"2012-09-05T20:39:09","guid":{"rendered":"http:\/\/www.lasalsavive.org\/portale\/?p=3921"},"modified":"2012-09-15T14:00:44","modified_gmt":"2012-09-15T13:00:44","slug":"no-sirvo-pa-queso-la-maxima-79","status":"publish","type":"post","link":"https:\/\/www.lasalsavive.org\/portale\/2012\/09\/05\/no-sirvo-pa-queso-la-maxima-79\/","title":{"rendered":"No sirvo pa&#8217; queso, il nuovo singolo dell&#8217;orchestra La Maxima 79"},"content":{"rendered":"<p>L&#8217;etichetta Smayra Publishing e&#8217; lieta di presentarvi il primo GUAGUANCO dell&#8217;orchestra <strong>LA MAXIMA 79<\/strong> la nuova formazione che ha come obiettivo principale quello di creare canzoni nel puro stile anni 70 cercando di esaudire in tutto e per tutto i desideri dei ballerini che ogni settimana riempiono i congressi di salsa di tutto il mondo.<\/p>\n<figure id=\"attachment_3924\" aria-describedby=\"caption-attachment-3924\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3924\" title=\"La Maxima 79\" src=\"http:\/\/www.lasalsavive.org\/portale\/wp-content\/uploads\/2012\/09\/copertina-per-cd-baby-1-300x300.jpg\" alt=\"La Maxima 79, no sirvo pa' queso\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.lasalsavive.org\/portale\/wp-content\/uploads\/2012\/09\/copertina-per-cd-baby-1-300x300.jpg 300w, https:\/\/www.lasalsavive.org\/portale\/wp-content\/uploads\/2012\/09\/copertina-per-cd-baby-1-150x150.jpg 150w, https:\/\/www.lasalsavive.org\/portale\/wp-content\/uploads\/2012\/09\/copertina-per-cd-baby-1-400x400.jpg 400w, https:\/\/www.lasalsavive.org\/portale\/wp-content\/uploads\/2012\/09\/copertina-per-cd-baby-1.jpg 567w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-3924\" class=\"wp-caption-text\">La Maxima 79, no sirvo pa&#8217; queso<\/figcaption><\/figure>\n<p>Nasce cosi dopo due cha cha cha di successo come &#8220;<strong>Mi Chula<\/strong> &#8221; e &#8220;<strong>Habia Cavour<\/strong> &#8221; il primo GUAGUANCO &#8216; &#8221; <strong>NO SIRVO PA&#8217; QUESO<\/strong>&#8221; che sar\u00e0 il singolo che precede l&#8217;uscita del disco dell&#8217;orchestra intitolato &#8220;<strong>Regresando al Guaguanco<\/strong>&#8221; e previsto per i primi giorni del 2013 .<\/p>\n<p><center><iframe loading=\"lazy\" width=\"420\" height=\"315\" src=\"http:\/\/www.youtube.com\/embed\/td67KKgVBLw\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p><b>La presentazione del disco al nono compleanno LaSalsaVive l&#8217;8 settembre 2012<\/b><\/p>\n<p><\/center><\/p>\n<p><center><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/olLzUoFdyoA\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/center>Canta El Guille direttamente da Cuba e le idee , il progetto e gli arrangiamenti sono curati da i due leader dell&#8217;orchestra Massimo Scalici e Fabrizio Zoro mentre i musicisti sono tutti professionisti del settore e suonano dal latino al jazz puro.<\/p>\n<p>Il brano sar\u00e0 presentato ufficialmente da <strong>Fabrizio Zoro<\/strong> l&#8217;8 settembre al Don Chisciotte di Galliera, in occasione del nono compleanno LaSalsaVive.<\/p>\n<p>Per ascoltare il promo di &#8220;No sirvo pa&#8217; queso&#8221; in anteprima:<br \/>\n[audio:http:\/\/www.lasalsavive.org\/portale\/audio\/quiz.mp3] (Flash player)<\/p>\n<p>[jwplayer mediaid=&#8221;3949&#8243;] (HTML5 Iphone, Ipad player)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;etichetta Smayra Publishing e&#8217; lieta di presentarvi il primo GUAGUANCO dell&#8217;orchestra LA MAXIMA 79 la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3924,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[427,6],"tags":[936,932,935,934,933],"class_list":["post-3921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-recensioni","tag-fabrizio-zoro","tag-la-maxima-79","tag-massimo-scalici","tag-no-sirvo-pa-queso","tag-regresando-al-guaguanco"],"_links":{"self":[{"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/posts\/3921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/comments?post=3921"}],"version-history":[{"count":22,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/posts\/3921\/revisions"}],"predecessor-version":[{"id":3948,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/posts\/3921\/revisions\/3948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/media\/3924"}],"wp:attachment":[{"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/media?parent=3921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/categories?post=3921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/tags?post=3921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}