{"id":7746,"date":"2017-09-11T11:13:49","date_gmt":"2017-09-11T10:13:49","guid":{"rendered":"http:\/\/www.lasalsavive.org\/portale\/?p=7746"},"modified":"2026-04-05T09:07:04","modified_gmt":"2026-04-05T08:07:04","slug":"lasalsavive-e-sono-quattordici","status":"publish","type":"post","link":"https:\/\/www.lasalsavive.org\/portale\/2017\/09\/11\/lasalsavive-e-sono-quattordici\/","title":{"rendered":"LaSalsaVive e sono quattordici!"},"content":{"rendered":"<p>Finalmente trovo un attimo di tempo per scrivere due righe sul 14 compleanno LaSalsaVive&#8230;intanto vorrei ringraziare Andrea e Samuele e la loro famiglia che nonostante le avverse condizioni climatiche hanno svolto un lavoro INCREDIBILE! Poi li ringrazio perch\u00e8 tornare dopo un anno e ritrovare tutto come era rimasto, b\u00e8, \u00e8 una bellissima cosa! Ogni anno \u00e8 sempre uguale, si parte con una fortissima carica che comprende sia la tensione legata all&#8217;organizzazione che quella per la riuscita di tutto, affinch\u00e8 tutti voi possiate passare una notte UNICA e INDIMENTICABILE. Speriamo di esserci riusciti anche questa volta nonostante il tempo abbia cercato di farci la&#8230;festa! \ud83d\ude42 Quindi non posso non ringraziare TUTTI voi, gli assoluti protagonisti insieme alla musica di questa festa, voi che ogni anno ci rinnovate la fiducia e continuate a muovervi da ogni angolo d&#8217;Italia e dall&#8217;estero per vivere una sola notte fatta di emozioni, di incontri, di gioia di condividere questa grande passione che si chiama SALSA. E naturalmente grazie anche a tutti i dj che hanno condiviso la consolle in modo ESEMPLARE, grazie ragazzi, siete stati veramente GRANDI! Concludo ringraziando la nostra cara amica Jessica che \u00e8 venuta apposta da Parigi per stare insieme ai suoi amici, la nostra sorellina acquisita Una insieme a cui tutto questo nacque un po&#8217; di anni fa per gioco, e naturalmente al fratellone (questo vero&#8230; \ud83d\ude42 ) che condivide con me l&#8217;organizzazione degli eventi LaSalsaVive. Grazie grazie grazie e&#8230;appuntamento al 22 settembre 2017 al Byblos di Misano Adriatico per un&#8217;altra notte magica!<\/p>\n<figure id=\"attachment_7747\" aria-describedby=\"caption-attachment-7747\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7747\" src=\"http:\/\/www.lasalsavive.org\/portale\/wp-content\/uploads\/2017\/09\/20170910_024506-300x169.jpg\" alt=\"LaSalsaVive, 14 compleanno, il taglio della torta!\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.lasalsavive.org\/portale\/wp-content\/uploads\/2017\/09\/20170910_024506-300x169.jpg 300w, https:\/\/www.lasalsavive.org\/portale\/wp-content\/uploads\/2017\/09\/20170910_024506-768x432.jpg 768w, https:\/\/www.lasalsavive.org\/portale\/wp-content\/uploads\/2017\/09\/20170910_024506-400x225.jpg 400w, https:\/\/www.lasalsavive.org\/portale\/wp-content\/uploads\/2017\/09\/20170910_024506.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-7747\" class=\"wp-caption-text\">LaSalsaVive, 14 compleanno, il taglio della torta!<\/figcaption><\/figure>\n<h2><a href=\"https:\/\/www.lasalsavive.org\/foto\/lasalsavive.org\/LaSalsaVive_14_compleanno_100917_web\">Clicca qui per vedere le foto!<\/a><\/h2>\n<p><iframe loading=\"lazy\" title=\"14 compleanno LaSalsaVive parte 1\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/5JQyODbnk-g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"14 compleanno LaSalsaVive parte 2\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/I_fcAVclnZ8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finalmente trovo un attimo di tempo per scrivere due righe sul 14 compleanno LaSalsaVive&#8230;intanto vorrei&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[427],"tags":[1480,314,1329,544,1332,1334],"class_list":["post-7746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-14-compleanno-lasalsavive","tag-don-chisciotte","tag-lasalsavive","tag-salsa","tag-salsa-classica","tag-salsa-dura"],"_links":{"self":[{"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/posts\/7746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/comments?post=7746"}],"version-history":[{"count":10,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/posts\/7746\/revisions"}],"predecessor-version":[{"id":11942,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/posts\/7746\/revisions\/11942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/media\/7747"}],"wp:attachment":[{"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/media?parent=7746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/categories?post=7746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasalsavive.org\/portale\/wp-json\/wp\/v2\/tags?post=7746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}